{"id":6853,"date":"2025-09-29T10:26:56","date_gmt":"2025-09-29T14:26:56","guid":{"rendered":"https:\/\/pscpartners.ca\/resource\/stades-de-la-fibrose-hepatique-par-rapport-a-la-cirrhose-dans-la-csp\/"},"modified":"2025-11-26T14:58:11","modified_gmt":"2025-11-26T19:58:11","slug":"stades-de-la-fibrose-hepatique-par-rapport-a-la-cirrhose-dans-la-csp","status":"publish","type":"resource","link":"https:\/\/pscpartners.ca\/fr\/resource\/stades-de-la-fibrose-hepatique-par-rapport-a-la-cirrhose-dans-la-csp\/","title":{"rendered":"Stades de la fibrose h\u00e9patique par rapport \u00e0 la cirrhose dans la CSP"},"content":{"rendered":"<div class=\"gb-container gb-container-da796622 psc-container\">\n\n<p>Toute personne atteinte de cholangite scl\u00e9rosante primitive (CSP) a peut-\u00eatre entendu son m\u00e9decin parler de \u00ab\u00a0fibrose\u00a0\u00bb ou de \u00ab\u00a0cirrhose\u00a0\u00bb lors de bilans de sant\u00e9 ou de FibroScan (une proc\u00e9dure non invasive similaire \u00e0 une \u00e9chographie). Ces mots peuvent faire peur, mais le fait d&rsquo;en conna\u00eetre la signification peut aider les patients et leurs m\u00e9decins \u00e0 faire les meilleurs choix pour la sant\u00e9 du patient. Rappelez-vous que de nombreuses personnes vivent une vie active et bien remplie pendant de nombreuses ann\u00e9es avec la CSP.  <\/p>\n\n\n<div class=\"gb-container gb-container-ceff609d\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/vr2.verticalresponse.com\/s\/websitesignupform18691697673980\" target=\"_blank\" rel=\" noreferrer noopener\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"728\" height=\"90\" src=\"https:\/\/pscpartners.ca\/wp-content\/uploads\/2025\/05\/Subscribe-banner-ad_leaderboard1.png\" alt=\"\" class=\"wp-image-6854\" srcset=\"https:\/\/pscpartners.ca\/wp-content\/uploads\/2025\/05\/Subscribe-banner-ad_leaderboard1.png 728w, https:\/\/pscpartners.ca\/wp-content\/uploads\/2025\/05\/Subscribe-banner-ad_leaderboard1-300x37.png 300w\" sizes=\"auto, (max-width: 728px) 100vw, 728px\" \/><\/a><\/figure>\n<\/div>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\">Qu&rsquo;est-ce que la fibrose h\u00e9patique ?<\/h3>\n\n\n\n<p>La fibrose est le terme m\u00e9dical qui d\u00e9signe la \u00ab\u00a0cicatrisation du foie\u00a0\u00bb. Tout comme la peau peut former une cicatrice apr\u00e8s une blessure, le foie cr\u00e9e du tissu cicatriciel lorsque les canaux biliaires s&rsquo;enflamment pour tenter de r\u00e9parer les dommages. <\/p>\n\n\n\n<p>Au fil du temps, une fibrose peut se d\u00e9velopper lentement. La vitesse de progression est diff\u00e9rente pour chaque personne atteinte de CSP. De nombreuses personnes vivent avec une fibrose l\u00e9g\u00e8re ou mod\u00e9r\u00e9e, souvent sans sympt\u00f4mes.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Stades de fibrose<\/h3>\n\n\n\n<p>Si vous \u00eates atteint de CSP, les m\u00e9decins peuvent parler de fibrose en \u00ab\u00a0stades\u00a0\u00bb ou utiliser des termes tels que \u00ab\u00a0F0\u00a0\u00bb, \u00ab\u00a0F1\u00a0\u00bb, etc. Le principal syst\u00e8me utilis\u00e9 pour la fibrose du CSP s&rsquo;appelle le syst\u00e8me Ludwig, tandis que l&rsquo;autre syst\u00e8me utilis\u00e9 pour la fibrose en g\u00e9n\u00e9ral s&rsquo;appelle le syst\u00e8me METVAR. <\/p>\n\n\n\n<p><em>Le syst\u00e8me Ludwig (stades 1 \u00e0 4) : Principalement utilis\u00e9 pour les CSP<\/em><br\/><strong>Stade 1<\/strong> &#8211; Tr\u00e8s peu de cicatrices dans les coins\/zones d&rsquo;entr\u00e9e de votre foie, appel\u00e9es zones portales.<br\/><strong>Stade 2<\/strong> &#8211; Les cicatrices commencent \u00e0 s&rsquo;\u00e9tendre en dehors des zones portales, mais elles ne sont pas reli\u00e9es entre elles.<br\/><strong>Stade 3 <\/strong>&#8211; Les cicatrices commencent \u00e0 se relier entre elles.<br\/><strong>Stade 4 <\/strong>&#8211; Les cicatrices sont maintenant \u00e9tendues et reli\u00e9es entre elles, ce qui conduit \u00e0 la cirrhose (cicatrices permanentes en forme de \u00ab\u00a0nid d&rsquo;abeille\u00a0\u00bb).<\/p>\n\n\n\n<p><em>Le syst\u00e8me METVAR (F0-F4) : G\u00e9n\u00e9ralit\u00e9s pour toute maladie du foie<\/em><br\/> F0 &#8211; Pas de fibrose : Pas de cicatrisation visible<br\/><strong>F1<\/strong> &#8211; Fibrose l\u00e9g\u00e8re : Petites r\u00e9gions touch\u00e9es.<br\/><strong>F2<\/strong> &#8211; Fibrose mod\u00e9r\u00e9e<br\/> F3 &#8211; Fibrose s\u00e9v\u00e8re : Les zones cicatricielles commencent \u00e0 se connecter. <br\/><strong>F4<\/strong> &#8211; Cirrhose : Beaucoup de tissu cicatriciel autour du foie.<\/p>\n\n\n\n<p>Dans les premiers stades de la fibrose, les sympt\u00f4mes sont g\u00e9n\u00e9ralement absents. Dans les stades plus avanc\u00e9s, certains <a href=\"https:\/\/pscpartners.ca\/fr\/resource\/symptomes-courants-de-la-csp\/\">sympt\u00f4mes pr\u00e9coces de la CSP<\/a> peuvent \u00eatre pr\u00e9sents, comme la fatigue, les d\u00e9mangeaisons et la modification des valeurs des tests sanguins tels que les tests de la fonction h\u00e9patique (LFT). Les deux syst\u00e8mes aident les m\u00e9decins \u00e0 comprendre l&rsquo;\u00e9tat de sant\u00e9 du foie et \u00e0 le traiter au mieux. Demandez au m\u00e9decin quel syst\u00e8me il utilise et ce que signifie votre stade ou votre score actuel.   <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Qu&rsquo;est-ce que la cirrhose du foie ?<\/h3>\n\n\n\n<p>La cirrhose survient lorsque le tissu cicatriciel a remplac\u00e9 une grande partie du tissu h\u00e9patique normal (stade 4 de Ludwig ou METVAR F4). Tous les patients atteints de CSP ne d\u00e9veloppent pas une cirrhose. La cirrhose elle-m\u00eame est divis\u00e9e en deux stades cliniques. Certains chercheurs l&rsquo;ont m\u00eame divis\u00e9e en 4 sous-stades :   <\/p>\n\n\n\n<p>La <em>cirrhose compens\u00e9e<\/em> est le stade pr\u00e9coce de la cirrhose o\u00f9 l&rsquo;organisme \u00ab\u00a0compense\u00a0\u00bb les l\u00e9sions du foie. Le foie fonctionne encore suffisamment bien, de sorte que les sympt\u00f4mes de la cirrhose sont l\u00e9gers ou inexistants. Les personnes atteintes de cirrhose m\u00e8nent encore une vie active \u00e0 ce stade.    <\/p>\n\n\n\n<p>L&rsquo;hypertension portale peut \u00eatre pr\u00e9sente en cas de cirrhose compens\u00e9e. En cas d&rsquo;hypertension portale, le tissu cicatriciel augmente la pression dans un vaisseau sp\u00e9cial appel\u00e9 veine porte, qui transporte le sang de l&rsquo;estomac, des intestins, de la rate et du pancr\u00e9as vers le foie pour le filtrer. L&rsquo;augmentation de la pression peut amener le sang \u00e0 emprunter d&rsquo;autres veines pour contourner le foie (c&rsquo;est ainsi que l&rsquo;organisme \u00ab\u00a0compense\u00a0\u00bb), ce qui peut \u00e9tirer et affaiblir les vaisseaux au fil du temps.    <\/p>\n\n\n\n<p><strong>Sous-stade 1<\/strong> &#8211; Pas de veines gonfl\u00e9es (varices), pas d&rsquo;accumulation de liquide dans l&rsquo;abdomen (ascite)<br\/><strong>Sous-stade 2<\/strong> &#8211; Pr\u00e9sence de varices, mais pas de saignement ni d&rsquo;ascite<\/p>\n\n\n\n<p>La <em>cirrhose d\u00e9compens\u00e9e<\/em> est le dernier stade de la cirrhose o\u00f9 l&rsquo;organisme ne peut pas compenser les l\u00e9sions du foie en raison d&rsquo;un nombre insuffisant de cellules saines. C&rsquo;est \u00e0 ce stade que les sympt\u00f4mes commencent \u00e0 se manifester : <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ascite<\/li>\n\n\n\n<li>Saignement variqueux (vomissements de sang ou selles noires)<\/li>\n\n\n\n<li>Enc\u00e9phalopathie h\u00e9patique (confusion, somnolence)<\/li>\n\n\n\n<li>Jaunisse (jaunissement de la peau et des yeux)<\/li>\n<\/ul>\n\n\n\n<p><strong>Sous-stade 3<\/strong> &#8211; Premi\u00e8re d\u00e9compensation (un des sympt\u00f4mes ci-dessus)<br\/><strong>Sous-stade 4<\/strong> &#8211; Complications r\u00e9p\u00e9t\u00e9es<\/p>\n\n\n\n<p>Cependant, les traitements de ces complications se sont consid\u00e9rablement am\u00e9lior\u00e9s, permettant \u00e0 de nombreuses personnes de b\u00e9n\u00e9ficier d&rsquo;un soulagement significatif des sympt\u00f4mes et d&rsquo;une meilleure qualit\u00e9 de vie. Certaines personnes connaissent m\u00eame une recompensation, c&rsquo;est-\u00e0-dire une am\u00e9lioration de la fonction h\u00e9patique apr\u00e8s un traitement r\u00e9ussi. En fin de compte, la transplantation reste l&rsquo;option la plus efficace pour les stades avanc\u00e9s de la cirrhose, car elle peut am\u00e9liorer consid\u00e9rablement l&rsquo;\u00e9tat de sant\u00e9 et la qualit\u00e9 de vie d&rsquo;une personne.  <\/p>\n\n\n\n<p><strong>Gardez espoir et restez en contact \u00e9troit avec votre \u00e9quipe soignante. Ils sont vos partenaires dans la gestion de la CSP et le soutien de votre sant\u00e9 h\u00e9patique. Si vous souhaitez entrer en contact avec d&rsquo;autres personnes touch\u00e9es par la CSP, veuillez consulter les <a href=\"https:\/\/pscpartners.ca\/fr\/nouvelles-et-evenements\/\">groupes de soutien en personne et virtuels (Zoom Room) de<\/a> Partenaires CSP.  <\/strong><\/p>\n\n<\/div>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toute personne atteinte de cholangite scl\u00e9rosante primitive (CSP) a peut-\u00eatre entendu son m\u00e9decin parler de \u00ab\u00a0fibrose\u00a0\u00bb ou de \u00ab\u00a0cirrhose\u00a0\u00bb lors de bilans de sant\u00e9 ou de FibroScan (une proc\u00e9dure non invasive similaire \u00e0 une \u00e9chographie). Ces mots peuvent faire peur, mais le fait d&rsquo;en conna\u00eetre la signification peut aider les patients et leurs m\u00e9decins \u00e0 &#8230; <a title=\"Stades de la fibrose h\u00e9patique par rapport \u00e0 la cirrhose dans la CSP\" class=\"read-more\" href=\"https:\/\/pscpartners.ca\/fr\/resource\/stades-de-la-fibrose-hepatique-par-rapport-a-la-cirrhose-dans-la-csp\/\" aria-label=\"En savoir plus sur Stades de la fibrose h\u00e9patique par rapport \u00e0 la cirrhose dans la CSP\">Lire plus<\/a><\/p>\n","protected":false},"featured_media":6839,"template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Les diff\u00e9rents stades de la fibrose et de la cirrhose dans les maladies du foie","_seopress_titles_desc":"Comprendre la diff\u00e9rence entre la fibrose et la cirrhose et comment ces conditions \u00e9voluent avec la maladie du foie CSP.","_seopress_robots_index":"","_seopress_analysis_target_kw":""},"resource-category":[17],"class_list":["post-6853","resource","type-resource","status-publish","has-post-thumbnail","hentry","resource-category-advancing-psc"],"acf":[],"_links":{"self":[{"href":"https:\/\/pscpartners.ca\/fr\/wp-json\/wp\/v2\/resource\/6853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pscpartners.ca\/fr\/wp-json\/wp\/v2\/resource"}],"about":[{"href":"https:\/\/pscpartners.ca\/fr\/wp-json\/wp\/v2\/types\/resource"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pscpartners.ca\/fr\/wp-json\/wp\/v2\/media\/6839"}],"wp:attachment":[{"href":"https:\/\/pscpartners.ca\/fr\/wp-json\/wp\/v2\/media?parent=6853"}],"wp:term":[{"taxonomy":"resource-category","embeddable":true,"href":"https:\/\/pscpartners.ca\/fr\/wp-json\/wp\/v2\/resource-category?post=6853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}